{"id":8,"date":"2022-12-19T21:48:25","date_gmt":"2022-12-19T21:48:25","guid":{"rendered":"http:\/\/www.parrocchietuscania.it\/chiesatuscania\/?p=8"},"modified":"2022-12-19T21:48:25","modified_gmt":"2022-12-19T21:48:25","slug":"ti-diamo-il-benvenuto-nelleditor-gutenberg","status":"publish","type":"post","link":"https:\/\/www.parrocchietuscania.it\/chiesatuscania\/ti-diamo-il-benvenuto-nelleditor-gutenberg\/","title":{"rendered":"Ti diamo il benvenuto nell&#8217;editor Gutenberg"},"content":{"rendered":"\r\n<div class=\"wp-block-cover has-background-dim alignwide\" style=\"background-image: url('https:\/\/cldup.com\/Fz-ASbo2s3.jpg');\">\r\n<div class=\"wp-block-cover__inner-container is-layout-flow wp-block-cover-is-layout-flow\">\r\n<p class=\"has-text-align-center has-white-color has-text-color has-large-font-size wp-block-paragraph\">Di montagne e macchine da stampa<\/p>\r\n<\/div>\r\n<\/div>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">L'obiettivo di questo nuovo editor \u00e8 di rendere l'aggiunta di contenuto con formattazione avanzata in WordPress semplice e piacevole. L'intero articolo \u00e8 composto da <em>pezzi di contenuto<\/em> \u2014un po' simili ai mattoncini LEGO\u2014 che puoi muovere e con cui puoi interagire. Muovi il puntatore e noterai i vari blocchi evidenziarsi con bordi e frecce. Premi le frecce per riposizionare velocemente i blocchi, evitando la paura di perdere qualcosa durante il copia e incolla.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Quello che stai leggendo adesso \u00e8 un <strong>blocco di testo<\/strong> il pi\u00f9 semplice di tutti i blocchi. Il blocco di testo ha le sue opzioni per essere liberamente mosso nell'articolo...<\/p>\r\n\r\n\r\n\r\n<p class=\"has-text-align-right wp-block-paragraph\">... come questo, allineato a destra.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Anche i titoli sono blocchi separati, i quali aiutano a strutturare e organizzare il tuo contenuto.<\/p>\r\n\r\n\r\n\r\n<h2 class=\"wp-block-heading\">Un'immagine vale pi\u00f9 di mille parole<\/h2>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Gestire immagini e media con la massima attenzione \u00e8 un obiettivo primario del nuovo editor. Speriamo che troverai gli aspetti di aggiungere didascalie o di rendere le tue foto a larghezza piena pi\u00f9 facili e solidi di prima.<\/p>\r\n\r\n\r\n\r\n<div class=\"wp-block-image\">\r\n<figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/cldup.com\/cXyG__fTLN.jpg\" alt=\"Panorama stupendo\" \/>\r\n<figcaption>Se il tuo tema lo supporta vedrai un pulsante \"larghezza ampia\" nella barra degli strumenti dell'immagine. Provalo.<\/figcaption>\r\n<\/figure>\r\n<\/div>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Prova a selezionare e rimuovere o modificare la didascalia, ora non devi pi\u00f9 stare attento nel selezionare l'immagine o altro testo per errore e rovinarne la presentazione.<\/p>\r\n\r\n\r\n\r\n<h2 class=\"wp-block-heading\">Lo strumento di <em>inserimento<\/em><\/h2>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Immagina che tutto quello che WordPress pu\u00f2 fare sia disponibile velocemente e nella stessa posizione dell'interfaccia. Nessuna necessit\u00e0 di capire tag HTML e classi o ricordare le complicate sintassi dei shortcode. \u00c8 l'anima che sta dietro allo strumento di inserimento \u2014il pulsante <code>(+)<\/code> che vedi vicino all'editor\u2014 che ti permette di scorrere tutti i blocchi di contenuto disponibili e aggiungerli nel tuo articolo. Plugin e temi possono registrare i loro propri blocchi, offrendo cos\u00ec ogni tipo di possibilit\u00e0 per formattazioni avanzate e pubblicazione.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Provalo, potresti scoprire cosa WordPress pu\u00f2 gi\u00e0 aggiungere nei tuoi articoli che non ti aspetti. Ecco un elenco di cosa puoi trovare in questo momento:<\/p>\r\n\r\n\r\n\r\n<ul class=\"wp-block-list\">\r\n<li>Testi e titoli<\/li>\r\n<li>Immagini e video<\/li>\r\n<li>Gallerie<\/li>\r\n<li>Oggetti da incorporare come YouTube, Tweet o altri articoli di WordPress.<\/li>\r\n<li>Blocchi di layout come pulsanti, immagini a tutto schermo (hero), separatori, ecc ecc.<\/li>\r\n<li>Ed <em>elenchi<\/em> come questo naturalmente \ud83d\ude42<\/li>\r\n<\/ul>\r\n\r\n\r\n<hr class=\"wp-block-separator\" \/>\r\n\r\n\r\n<h2 class=\"wp-block-heading\">Modifiche visuali<\/h2>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Un enorme beneficio dei blocchi \u00e8 che puoi modificarli dove sono e modificare il tuo contenuto direttamente. Invece di avere campi per modificare cose come la fonte di una citazione o il testo di un pulsante, puoi cambiare direttamente il contenuto. Prova a modificare la citazione seguente:<\/p>\r\n\r\n\r\n\r\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\r\n<p>L'editor prover\u00e0 a creare una nuova esperienza di costruzione di pagine e articoli che agevoler\u00e0 la scrittura di articoli con formattazione avanzata, e con i \u201cblocchi\u201d render\u00e0 semplice quello che oggi \u00e8 ottenuto con shortcode, HTML personalizzato ed embed discovery di \u201cprovenienza incerta\u201d.<\/p>\r\n<cite>Matt Mullenweg, 2017<\/cite><\/blockquote>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">L'informazione corrispondente alla fonte della citazione \u00e8 un campo di testo separato, simile alle didascalie sotto le immagini, cos\u00ec la struttura della citazione \u00e8 protetta anche se selezioni, modifichi o rimuovi la fonte. \u00c8 sempre facile aggiungerla di nuovo.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">I blocchi possono essere qualsiasi cosa di cui hai bisogno. Per esempio potresti voler aggiungere una citazione non invasiva come parte della composizione del tuo testo, oppure potresti preferire visualizzarne una gigante. Tutte queste opzioni sono disponibili con lo strumento di inserimento.<\/p>\r\n\r\n\r\n\r\n<figure class=\"wp-block-gallery columns-2 is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\r\n<ul class=\"blocks-gallery-grid\">\r\n<li class=\"blocks-gallery-item\">\r\n<figure><img decoding=\"async\" src=\"https:\/\/cldup.com\/n0g6ME5VKC.jpg\" alt=\"\" \/><\/figure>\r\n<\/li>\r\n<li class=\"blocks-gallery-item\">\r\n<figure><img decoding=\"async\" src=\"https:\/\/cldup.com\/ZjESfxPI3R.jpg\" alt=\"\" \/><\/figure>\r\n<\/li>\r\n<li class=\"blocks-gallery-item\">\r\n<figure><img decoding=\"async\" src=\"https:\/\/cldup.com\/EKNF8xD2UM.jpg\" alt=\"\" \/><\/figure>\r\n<\/li>\r\n<\/ul>\r\n<\/figure>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Puoi cambiare la quantit\u00e0 di colonne delle tue gallerie trascinando un selettore nella gestione del blocco della barra laterale.<\/p>\r\n\r\n\r\n\r\n<h2 class=\"wp-block-heading\">Formattazione avanzata dei media<\/h2>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Se combini i nuovi allineamenti <strong>a larghezza ampia<\/strong> e <strong>a larghezza piena<\/strong> con le gallerie, puoi creare un layout multimediale molto avanzato, molto velocemente:<\/p>\r\n\r\n\r\n\r\n<figure class=\"wp-block-image alignfull\"><img decoding=\"async\" src=\"https:\/\/cldup.com\/8lhI-gKnI2.jpg\" alt=\"L'accessibilit\u00e0 \u00e8 importante \u2014 non dimenticare l'attributo alt dell'immagine\" \/><\/figure>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Certo, l'immagine a larghezza piena pu\u00f2 essere molto grande. Ma qualche volta l'immagine lo merita.<\/p>\r\n\r\n\r\n\r\n<figure class=\"wp-block-gallery alignwide columns-2 is-cropped wp-block-gallery-2 is-layout-flex wp-block-gallery-is-layout-flex\">\r\n<ul class=\"blocks-gallery-grid\">\r\n<li class=\"blocks-gallery-item\">\r\n<figure><img decoding=\"async\" src=\"https:\/\/cldup.com\/_rSwtEeDGD.jpg\" alt=\"\" \/><\/figure>\r\n<\/li>\r\n<li class=\"blocks-gallery-item\">\r\n<figure><img decoding=\"async\" src=\"https:\/\/cldup.com\/L-cC3qX2DN.jpg\" alt=\"\" \/><\/figure>\r\n<\/li>\r\n<\/ul>\r\n<\/figure>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Quella sopra \u00e8 una galleria con sole due immagini. \u00c8 un modo facile di creare layout ad impatto visivo, senza dover combattere con i float. Puoi anche riconvertire facilmente la galleria in immagini individuali, utilizzando la funzione di cambio blocco.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Qualsiasi blocco pu\u00f2 usufruire di questi allineamenti. Anche i blocchi incorporati hanno i loro e sono gi\u00e0 predisposti per essere responsivi:<\/p>\r\n\r\n\r\n\r\n<figure class=\"wp-block-embed-vimeo alignwide wp-block-embed is-type-video is-provider-vimeo wp-has-aspect-ratio wp-embed-aspect-16-9\">\r\n<div class=\"wp-block-embed__wrapper\">https:\/\/vimeo.com\/22439234<\/div>\r\n<\/figure>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Puoi sviluppare qualsiasi blocco tu voglia, statico o dinamico, decorativo o semplice. Ecco il blocco di una citazione in evidenza:<\/p>\r\n\r\n\r\n\r\n<figure class=\"wp-block-pullquote\">\r\n<blockquote>\r\n<p>Il codice \u00e8 poesia<\/p>\r\n<cite>La comunit\u00e0 di WordPress<\/cite><\/blockquote>\r\n<\/figure>\r\n\r\n\r\n\r\n<p class=\"has-text-align-center wp-block-paragraph\"><em> Se vuoi imparare di pi\u00f9 su come sviluppare blocchi aggiuntivi o sei interessato a dare una mano al progetto, vai al <a href=\"https:\/\/github.com\/WordPress\/gutenberg\">repository su GitHub<\/a>. <\/em><\/p>\r\n\r\n\r\n\r\n<div class=\"wp-block-button aligncenter\"><a class=\"wp-block-button__link\" href=\"https:\/\/github.com\/WordPress\/gutenberg\">Aiuta a costruire Gutenberg<\/a><\/div>\r\n\r\n\r\n<hr class=\"wp-block-separator\" \/>\r\n\r\n\r\n<p class=\"has-text-align-center wp-block-paragraph\">Grazie per aver testato Gutenberg!<\/p>\r\n\r\n\r\n\r\n<p class=\"has-text-align-center wp-block-paragraph\">\ud83d\udc4b<\/p>\r\n\r\n<p>&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>L&#8217;obiettivo di questo nuovo editor \u00e8 di rendere l&#8217;aggiunta di contenuto con formattazione avanzata in WordPress semplice e piacevole. L&#8217;intero articolo \u00e8 composto da pezzi di contenuto \u2014un po&#8217; simili ai mattoncini LEGO\u2014 che puoi muovere e con cui puoi interagire. Muovi il puntatore e noterai i vari blocchi evidenziarsi con bordi e frecce. Premi [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-8","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Ti diamo il benvenuto nell&#039;editor Gutenberg - Blog comunita parrocchiale Chiesa di Tuscania<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.parrocchietuscania.it\/chiesatuscania\/ti-diamo-il-benvenuto-nelleditor-gutenberg\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ti diamo il benvenuto nell&#039;editor Gutenberg - Blog comunita parrocchiale Chiesa di Tuscania\" \/>\n<meta property=\"og:description\" content=\"L&#8217;obiettivo di questo nuovo editor \u00e8 di rendere l&#8217;aggiunta di contenuto con formattazione avanzata in WordPress semplice e piacevole. L&#8217;intero articolo \u00e8 composto da pezzi di contenuto \u2014un po&#8217; simili ai mattoncini LEGO\u2014 che puoi muovere e con cui puoi interagire. Muovi il puntatore e noterai i vari blocchi evidenziarsi con bordi e frecce. Premi [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.parrocchietuscania.it\/chiesatuscania\/ti-diamo-il-benvenuto-nelleditor-gutenberg\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog comunita parrocchiale Chiesa di Tuscania\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/parrocchietuscania\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-12-19T21:48:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cldup.com\/cXyG__fTLN.jpg\" \/>\n<meta name=\"author\" content=\"umpasi.1949\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"umpasi.1949\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.parrocchietuscania.it\/chiesatuscania\/ti-diamo-il-benvenuto-nelleditor-gutenberg\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.parrocchietuscania.it\/chiesatuscania\/ti-diamo-il-benvenuto-nelleditor-gutenberg\/\"},\"author\":{\"name\":\"umpasi.1949\",\"@id\":\"https:\/\/www.parrocchietuscania.it\/chiesatuscania\/#\/schema\/person\/65ff7c05de34372b9c7f14d49484ef21\"},\"headline\":\"Ti diamo il benvenuto nell&#8217;editor Gutenberg\",\"datePublished\":\"2022-12-19T21:48:25+00:00\",\"dateModified\":\"2022-12-19T21:48:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.parrocchietuscania.it\/chiesatuscania\/ti-diamo-il-benvenuto-nelleditor-gutenberg\/\"},\"wordCount\":721,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.parrocchietuscania.it\/chiesatuscania\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.parrocchietuscania.it\/chiesatuscania\/ti-diamo-il-benvenuto-nelleditor-gutenberg\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/cldup.com\/cXyG__fTLN.jpg\",\"articleSection\":[\"Uncategorized\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.parrocchietuscania.it\/chiesatuscania\/ti-diamo-il-benvenuto-nelleditor-gutenberg\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.parrocchietuscania.it\/chiesatuscania\/ti-diamo-il-benvenuto-nelleditor-gutenberg\/\",\"url\":\"https:\/\/www.parrocchietuscania.it\/chiesatuscania\/ti-diamo-il-benvenuto-nelleditor-gutenberg\/\",\"name\":\"Ti diamo il benvenuto nell'editor Gutenberg - Blog comunita parrocchiale Chiesa di Tuscania\",\"isPartOf\":{\"@id\":\"https:\/\/www.parrocchietuscania.it\/chiesatuscania\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.parrocchietuscania.it\/chiesatuscania\/ti-diamo-il-benvenuto-nelleditor-gutenberg\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.parrocchietuscania.it\/chiesatuscania\/ti-diamo-il-benvenuto-nelleditor-gutenberg\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/cldup.com\/cXyG__fTLN.jpg\",\"datePublished\":\"2022-12-19T21:48:25+00:00\",\"dateModified\":\"2022-12-19T21:48:25+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.parrocchietuscania.it\/chiesatuscania\/ti-diamo-il-benvenuto-nelleditor-gutenberg\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.parrocchietuscania.it\/chiesatuscania\/ti-diamo-il-benvenuto-nelleditor-gutenberg\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.parrocchietuscania.it\/chiesatuscania\/ti-diamo-il-benvenuto-nelleditor-gutenberg\/#primaryimage\",\"url\":\"https:\/\/cldup.com\/cXyG__fTLN.jpg\",\"contentUrl\":\"https:\/\/cldup.com\/cXyG__fTLN.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.parrocchietuscania.it\/chiesatuscania\/ti-diamo-il-benvenuto-nelleditor-gutenberg\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.parrocchietuscania.it\/chiesatuscania\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ti diamo il benvenuto nell&#8217;editor Gutenberg\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.parrocchietuscania.it\/chiesatuscania\/#website\",\"url\":\"https:\/\/www.parrocchietuscania.it\/chiesatuscania\/\",\"name\":\"Blog comunit\u00e0 parrocchiale di Tuscania - Chiesa di Tuscania _Celebrazioni e Sante Messe Tuscania\",\"description\":\"Blog Chiesa di Tuscania  - parrocchia tuscania - celebrazioni e messe chiesa tuscania\",\"publisher\":{\"@id\":\"https:\/\/www.parrocchietuscania.it\/chiesatuscania\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.parrocchietuscania.it\/chiesatuscania\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.parrocchietuscania.it\/chiesatuscania\/#organization\",\"name\":\"Blog comunit\u00e0 parrocchiale di Tuscania - Chiesa di Tuscania _Celebrazioni e Sante Messe Tuscania\",\"url\":\"https:\/\/www.parrocchietuscania.it\/chiesatuscania\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.parrocchietuscania.it\/chiesatuscania\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/www.parrocchietuscania.it\/chiesatuscania\/wp-content\/uploads\/2022\/12\/cropped-logo_120_120_semitrasparente.gif\",\"contentUrl\":\"http:\/\/www.parrocchietuscania.it\/chiesatuscania\/wp-content\/uploads\/2022\/12\/cropped-logo_120_120_semitrasparente.gif\",\"width\":512,\"height\":512,\"caption\":\"Blog comunit\u00e0 parrocchiale di Tuscania - Chiesa di Tuscania _Celebrazioni e Sante Messe Tuscania\"},\"image\":{\"@id\":\"https:\/\/www.parrocchietuscania.it\/chiesatuscania\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/parrocchietuscania\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.parrocchietuscania.it\/chiesatuscania\/#\/schema\/person\/65ff7c05de34372b9c7f14d49484ef21\",\"name\":\"umpasi.1949\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.parrocchietuscania.it\/chiesatuscania\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/8ed0b3a4b3fd5362b66557a5f1aa6d0934bff1d1fc2324f8cd9747be786e38dc?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/8ed0b3a4b3fd5362b66557a5f1aa6d0934bff1d1fc2324f8cd9747be786e38dc?s=96&d=mm&r=g\",\"caption\":\"umpasi.1949\"},\"sameAs\":[\"http:\/\/www.parrocchietuscania.it\/chiesatuscania\"],\"url\":\"https:\/\/www.parrocchietuscania.it\/chiesatuscania\/author\/umpasi-1949\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ti diamo il benvenuto nell'editor Gutenberg - Blog comunita parrocchiale Chiesa di Tuscania","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.parrocchietuscania.it\/chiesatuscania\/ti-diamo-il-benvenuto-nelleditor-gutenberg\/","og_locale":"it_IT","og_type":"article","og_title":"Ti diamo il benvenuto nell'editor Gutenberg - Blog comunita parrocchiale Chiesa di Tuscania","og_description":"L&#8217;obiettivo di questo nuovo editor \u00e8 di rendere l&#8217;aggiunta di contenuto con formattazione avanzata in WordPress semplice e piacevole. L&#8217;intero articolo \u00e8 composto da pezzi di contenuto \u2014un po&#8217; simili ai mattoncini LEGO\u2014 che puoi muovere e con cui puoi interagire. Muovi il puntatore e noterai i vari blocchi evidenziarsi con bordi e frecce. Premi [&hellip;]","og_url":"https:\/\/www.parrocchietuscania.it\/chiesatuscania\/ti-diamo-il-benvenuto-nelleditor-gutenberg\/","og_site_name":"Blog comunita parrocchiale Chiesa di Tuscania","article_publisher":"https:\/\/www.facebook.com\/parrocchietuscania\/","article_published_time":"2022-12-19T21:48:25+00:00","og_image":[{"url":"https:\/\/cldup.com\/cXyG__fTLN.jpg"}],"author":"umpasi.1949","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"umpasi.1949","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.parrocchietuscania.it\/chiesatuscania\/ti-diamo-il-benvenuto-nelleditor-gutenberg\/#article","isPartOf":{"@id":"https:\/\/www.parrocchietuscania.it\/chiesatuscania\/ti-diamo-il-benvenuto-nelleditor-gutenberg\/"},"author":{"name":"umpasi.1949","@id":"https:\/\/www.parrocchietuscania.it\/chiesatuscania\/#\/schema\/person\/65ff7c05de34372b9c7f14d49484ef21"},"headline":"Ti diamo il benvenuto nell&#8217;editor Gutenberg","datePublished":"2022-12-19T21:48:25+00:00","dateModified":"2022-12-19T21:48:25+00:00","mainEntityOfPage":{"@id":"https:\/\/www.parrocchietuscania.it\/chiesatuscania\/ti-diamo-il-benvenuto-nelleditor-gutenberg\/"},"wordCount":721,"commentCount":0,"publisher":{"@id":"https:\/\/www.parrocchietuscania.it\/chiesatuscania\/#organization"},"image":{"@id":"https:\/\/www.parrocchietuscania.it\/chiesatuscania\/ti-diamo-il-benvenuto-nelleditor-gutenberg\/#primaryimage"},"thumbnailUrl":"https:\/\/cldup.com\/cXyG__fTLN.jpg","articleSection":["Uncategorized"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.parrocchietuscania.it\/chiesatuscania\/ti-diamo-il-benvenuto-nelleditor-gutenberg\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.parrocchietuscania.it\/chiesatuscania\/ti-diamo-il-benvenuto-nelleditor-gutenberg\/","url":"https:\/\/www.parrocchietuscania.it\/chiesatuscania\/ti-diamo-il-benvenuto-nelleditor-gutenberg\/","name":"Ti diamo il benvenuto nell'editor Gutenberg - Blog comunita parrocchiale Chiesa di Tuscania","isPartOf":{"@id":"https:\/\/www.parrocchietuscania.it\/chiesatuscania\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.parrocchietuscania.it\/chiesatuscania\/ti-diamo-il-benvenuto-nelleditor-gutenberg\/#primaryimage"},"image":{"@id":"https:\/\/www.parrocchietuscania.it\/chiesatuscania\/ti-diamo-il-benvenuto-nelleditor-gutenberg\/#primaryimage"},"thumbnailUrl":"https:\/\/cldup.com\/cXyG__fTLN.jpg","datePublished":"2022-12-19T21:48:25+00:00","dateModified":"2022-12-19T21:48:25+00:00","breadcrumb":{"@id":"https:\/\/www.parrocchietuscania.it\/chiesatuscania\/ti-diamo-il-benvenuto-nelleditor-gutenberg\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.parrocchietuscania.it\/chiesatuscania\/ti-diamo-il-benvenuto-nelleditor-gutenberg\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.parrocchietuscania.it\/chiesatuscania\/ti-diamo-il-benvenuto-nelleditor-gutenberg\/#primaryimage","url":"https:\/\/cldup.com\/cXyG__fTLN.jpg","contentUrl":"https:\/\/cldup.com\/cXyG__fTLN.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.parrocchietuscania.it\/chiesatuscania\/ti-diamo-il-benvenuto-nelleditor-gutenberg\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.parrocchietuscania.it\/chiesatuscania\/"},{"@type":"ListItem","position":2,"name":"Ti diamo il benvenuto nell&#8217;editor Gutenberg"}]},{"@type":"WebSite","@id":"https:\/\/www.parrocchietuscania.it\/chiesatuscania\/#website","url":"https:\/\/www.parrocchietuscania.it\/chiesatuscania\/","name":"Blog comunit\u00e0 parrocchiale di Tuscania - Chiesa di Tuscania _Celebrazioni e Sante Messe Tuscania","description":"Blog Chiesa di Tuscania  - parrocchia tuscania - celebrazioni e messe chiesa tuscania","publisher":{"@id":"https:\/\/www.parrocchietuscania.it\/chiesatuscania\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.parrocchietuscania.it\/chiesatuscania\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.parrocchietuscania.it\/chiesatuscania\/#organization","name":"Blog comunit\u00e0 parrocchiale di Tuscania - Chiesa di Tuscania _Celebrazioni e Sante Messe Tuscania","url":"https:\/\/www.parrocchietuscania.it\/chiesatuscania\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.parrocchietuscania.it\/chiesatuscania\/#\/schema\/logo\/image\/","url":"http:\/\/www.parrocchietuscania.it\/chiesatuscania\/wp-content\/uploads\/2022\/12\/cropped-logo_120_120_semitrasparente.gif","contentUrl":"http:\/\/www.parrocchietuscania.it\/chiesatuscania\/wp-content\/uploads\/2022\/12\/cropped-logo_120_120_semitrasparente.gif","width":512,"height":512,"caption":"Blog comunit\u00e0 parrocchiale di Tuscania - Chiesa di Tuscania _Celebrazioni e Sante Messe Tuscania"},"image":{"@id":"https:\/\/www.parrocchietuscania.it\/chiesatuscania\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/parrocchietuscania\/"]},{"@type":"Person","@id":"https:\/\/www.parrocchietuscania.it\/chiesatuscania\/#\/schema\/person\/65ff7c05de34372b9c7f14d49484ef21","name":"umpasi.1949","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.parrocchietuscania.it\/chiesatuscania\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/8ed0b3a4b3fd5362b66557a5f1aa6d0934bff1d1fc2324f8cd9747be786e38dc?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8ed0b3a4b3fd5362b66557a5f1aa6d0934bff1d1fc2324f8cd9747be786e38dc?s=96&d=mm&r=g","caption":"umpasi.1949"},"sameAs":["http:\/\/www.parrocchietuscania.it\/chiesatuscania"],"url":"https:\/\/www.parrocchietuscania.it\/chiesatuscania\/author\/umpasi-1949\/"}]}},"_links":{"self":[{"href":"https:\/\/www.parrocchietuscania.it\/chiesatuscania\/wp-json\/wp\/v2\/posts\/8","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.parrocchietuscania.it\/chiesatuscania\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.parrocchietuscania.it\/chiesatuscania\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.parrocchietuscania.it\/chiesatuscania\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.parrocchietuscania.it\/chiesatuscania\/wp-json\/wp\/v2\/comments?post=8"}],"version-history":[{"count":1,"href":"https:\/\/www.parrocchietuscania.it\/chiesatuscania\/wp-json\/wp\/v2\/posts\/8\/revisions"}],"predecessor-version":[{"id":9,"href":"https:\/\/www.parrocchietuscania.it\/chiesatuscania\/wp-json\/wp\/v2\/posts\/8\/revisions\/9"}],"wp:attachment":[{"href":"https:\/\/www.parrocchietuscania.it\/chiesatuscania\/wp-json\/wp\/v2\/media?parent=8"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.parrocchietuscania.it\/chiesatuscania\/wp-json\/wp\/v2\/categories?post=8"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.parrocchietuscania.it\/chiesatuscania\/wp-json\/wp\/v2\/tags?post=8"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}